{"id":47,"count":29,"description":"","link":"https:\/\/kchc.ca\/fr\/service-areas\/grossesse\/","name":"Grossesse","slug":"grossesse","taxonomy":"category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grossesse Archives - Centres de sant\u00e9 communautaires de Kingston<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kchc.ca\/fr\/service-areas\/grossesse\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grossesse Archives - Centres de sant\u00e9 communautaires de Kingston\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kchc.ca\/fr\/service-areas\/grossesse\/\" \/>\n<meta property=\"og:site_name\" content=\"Centres de sant\u00e9 communautaires de Kingston\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@KingstonCHC\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/service-areas\\\/grossesse\\\/\",\"url\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/service-areas\\\/grossesse\\\/\",\"name\":\"Grossesse Archives - Centres de sant\u00e9 communautaires de Kingston\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/service-areas\\\/grossesse\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/service-areas\\\/grossesse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Grossesse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/\",\"name\":\"Kingston Community Health Centres\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#organization\",\"name\":\"Kingston Community Health Centres\",\"url\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kchc.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/KCHC-logo.png\",\"contentUrl\":\"https:\\\/\\\/kchc.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/KCHC-logo.png\",\"width\":1096,\"height\":398,\"caption\":\"Kingston Community Health Centres\"},\"image\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KingstonCHC\\\/\",\"https:\\\/\\\/x.com\\\/KingstonCHC\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grossesse Archives - Centres de sant\u00e9 communautaires de Kingston","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kchc.ca\/fr\/service-areas\/grossesse\/","og_locale":"fr_FR","og_type":"article","og_title":"Grossesse Archives - Centres de sant\u00e9 communautaires de Kingston","og_url":"https:\/\/kchc.ca\/fr\/service-areas\/grossesse\/","og_site_name":"Centres de sant\u00e9 communautaires de Kingston","twitter_card":"summary_large_image","twitter_site":"@KingstonCHC","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/kchc.ca\/fr\/service-areas\/grossesse\/","url":"https:\/\/kchc.ca\/fr\/service-areas\/grossesse\/","name":"Grossesse Archives - Centres de sant\u00e9 communautaires de Kingston","isPartOf":{"@id":"https:\/\/kchc.ca\/fr\/#website"},"breadcrumb":{"@id":"https:\/\/kchc.ca\/fr\/service-areas\/grossesse\/#breadcrumb"},"inLanguage":"fr-FR"},{"@type":"BreadcrumbList","@id":"https:\/\/kchc.ca\/fr\/service-areas\/grossesse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kchc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Grossesse"}]},{"@type":"WebSite","@id":"https:\/\/kchc.ca\/fr\/#website","url":"https:\/\/kchc.ca\/fr\/","name":"Kingston Community Health Centres","description":"","publisher":{"@id":"https:\/\/kchc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kchc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kchc.ca\/fr\/#organization","name":"Kingston Community Health Centres","url":"https:\/\/kchc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kchc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/kchc.ca\/wp-content\/uploads\/2024\/06\/KCHC-logo.png","contentUrl":"https:\/\/kchc.ca\/wp-content\/uploads\/2024\/06\/KCHC-logo.png","width":1096,"height":398,"caption":"Kingston Community Health Centres"},"image":{"@id":"https:\/\/kchc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KingstonCHC\/","https:\/\/x.com\/KingstonCHC"]}]}},"_links":{"self":[{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/categories\/47","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/posts?categories=47"},{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/event?categories=47"},{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/program?categories=47"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}