{"id":3531,"date":"2025-03-13T13:38:40","date_gmt":"2025-03-13T17:38:40","guid":{"rendered":"https:\/\/kchc.ca\/programs\/neurodiversite-et-autisme-chez-ladulte\/"},"modified":"2025-04-15T11:45:47","modified_gmt":"2025-04-15T15:45:47","slug":"neurodiversite-et-autisme-chez-ladulte","status":"publish","type":"program","link":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/","title":{"rendered":"Neurodiversit\u00e9 et autisme chez l&rsquo;adulte"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il s&rsquo;agit d&rsquo;un atelier d&rsquo;une heure, soit virtuel\/en ligne, soit en personne. Les animateurs ont une exp\u00e9rience personnelle de la neurodivergence et\/ou de l&rsquo;autisme adulte, et le programme a \u00e9t\u00e9 d\u00e9velopp\u00e9 par un \u00e9ducateur form\u00e9 ayant \u00e9galement une exp\u00e9rience v\u00e9cue, en collaboration avec la communaut\u00e9 de pratique de la neuroaffirmation \u00e0 Kingston, en Ontario. <\/p>\n\n<p class=\"wp-block-paragraph\">Toute personne vivant dans le sud-est de l&rsquo;Ontario peut s&rsquo;inscrire. Aucune recommandation n&rsquo;est n\u00e9cessaire et le co\u00fbt est enti\u00e8rement gratuit. Nous sommes financ\u00e9s par le minist\u00e8re de la sant\u00e9 et des soins de longue dur\u00e9e.  <\/p>\n\n<p class=\"wp-block-paragraph\">Rejoignez-nous pour un \u00e9v\u00e9nement en ligne tr\u00e8s instructif sur la neurodiversit\u00e9 et l&rsquo;autisme chez les adultes ! D\u00e9couvrez les forces et les d\u00e9fis uniques des personnes sur le spectre autistique, ainsi que les d\u00e9fis quotidiens auxquels elles peuvent \u00eatre confront\u00e9es. Nos intervenants vous fourniront des informations et des conseils pr\u00e9cieux pour comprendre et soutenir les adultes neurodivergents dans divers aspects de la vie.  <\/p>\n\n<p class=\"wp-block-paragraph\">Que vous soyez novice en la mati\u00e8re ou que vous cherchiez \u00e0 approfondir vos connaissances, cet \u00e9v\u00e9nement est id\u00e9al pour tous ceux qui souhaitent en savoir plus sur la neurodiversit\u00e9 et l&rsquo;autisme chez les adultes. N&rsquo;h\u00e9sitez pas \u00e0 poser des questions tout au long de l&rsquo;atelier. <\/p>\n\n<p class=\"wp-block-paragraph\">Les th\u00e8mes abord\u00e9s sont les suivants<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Quelles sont les pathologies incluses dans la neurodivergence ?<\/li>\n\n\n\n<li>Importance de l&rsquo;identification de votre neurotype<\/li>\n\n\n\n<li>Les 3 piliers de l&rsquo;autisme<\/li>\n\n\n\n<li>Sensibilit\u00e9s sensorielles chez l&rsquo;adulte<\/li>\n\n\n\n<li>Grandes \u00e9motions<\/li>\n\n\n\n<li>Masquage et camouflage social<\/li>\n\n\n\n<li>Comp\u00e9tences d&rsquo;adaptation<\/li>\n\n\n\n<li>Stimulation<\/li>\n\n\n\n<li>Rassemblements neuroinclusifs<\/li>\n\n\n\n<li>et plus encore !<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">Nous proposons \u00e9galement un atelier \u00ab\u00a0Neurodiversit\u00e9 et TDAH chez l&rsquo;adulte\u00a0\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il s&rsquo;agit d&rsquo;un atelier d&rsquo;une heure, soit virtuel\/en ligne, soit en personne. Les animateurs ont une exp\u00e9rience personnelle de la neurodivergence et\/ou de l&rsquo;autisme adulte, et le programme a \u00e9t\u00e9 d\u00e9velopp\u00e9 par un \u00e9ducateur form\u00e9 ayant \u00e9galement une exp\u00e9rience v\u00e9cue, en collaboration avec la communaut\u00e9 de pratique de la neuroaffirmation \u00e0 Kingston, en Ontario. <\/p>\n","protected":false},"featured_media":3068,"template":"","categories":[43,45],"communities":[78],"class_list":["post-3531","program","type-program","status-publish","has-post-thumbnail","hentry","category-sante-et-bien-etre","category-sante-mentale","communities-adultes"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neurodiversit\u00e9 et autisme chez l&#039;adulte - Centres de sant\u00e9 communautaires de Kingston<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neurodiversit\u00e9 et autisme chez l&#039;adulte - Centres de sant\u00e9 communautaires de Kingston\" \/>\n<meta property=\"og:description\" content=\"Il s&#039;agit d&#039;un atelier d&#039;une heure, soit virtuel\/en ligne, soit en personne. Les animateurs ont une exp\u00e9rience personnelle de la neurodivergence et\/ou de l&#039;autisme adulte, et le programme a \u00e9t\u00e9 d\u00e9velopp\u00e9 par un \u00e9ducateur form\u00e9 ayant \u00e9galement une exp\u00e9rience v\u00e9cue, en collaboration avec la communaut\u00e9 de pratique de la neuroaffirmation \u00e0 Kingston, en Ontario.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/\" \/>\n<meta property=\"og:site_name\" content=\"Centres de sant\u00e9 communautaires de Kingston\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/KingstonCHC\/\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-15T15:45:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/kchc.ca\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-29T121732.905.png\" \/>\n\t<meta property=\"og:image:width\" content=\"851\" \/>\n\t<meta property=\"og:image:height\" content=\"315\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@KingstonCHC\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/programs\\\/neurodiversite-et-autisme-chez-ladulte\\\/\",\"url\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/programs\\\/neurodiversite-et-autisme-chez-ladulte\\\/\",\"name\":\"Neurodiversit\u00e9 et autisme chez l'adulte - Centres de sant\u00e9 communautaires de Kingston\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/programs\\\/neurodiversite-et-autisme-chez-ladulte\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/programs\\\/neurodiversite-et-autisme-chez-ladulte\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/kchc.ca\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Untitled-design-2025-01-29T121732.905.png\",\"datePublished\":\"2025-03-13T17:38:40+00:00\",\"dateModified\":\"2025-04-15T15:45:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/programs\\\/neurodiversite-et-autisme-chez-ladulte\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/kchc.ca\\\/fr\\\/programs\\\/neurodiversite-et-autisme-chez-ladulte\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/programs\\\/neurodiversite-et-autisme-chez-ladulte\\\/#primaryimage\",\"url\":\"https:\\\/\\\/kchc.ca\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Untitled-design-2025-01-29T121732.905.png\",\"contentUrl\":\"https:\\\/\\\/kchc.ca\\\/wp-content\\\/uploads\\\/2025\\\/01\\\/Untitled-design-2025-01-29T121732.905.png\",\"width\":851,\"height\":315},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/programs\\\/neurodiversite-et-autisme-chez-ladulte\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Programs\",\"item\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/programs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Neurodiversit\u00e9 et autisme chez l&#8217;adulte\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/\",\"name\":\"Kingston Community Health Centres\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#organization\",\"name\":\"Kingston Community Health Centres\",\"url\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/kchc.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/KCHC-logo.png\",\"contentUrl\":\"https:\\\/\\\/kchc.ca\\\/wp-content\\\/uploads\\\/2024\\\/06\\\/KCHC-logo.png\",\"width\":1096,\"height\":398,\"caption\":\"Kingston Community Health Centres\"},\"image\":{\"@id\":\"https:\\\/\\\/kchc.ca\\\/fr\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/KingstonCHC\\\/\",\"https:\\\/\\\/x.com\\\/KingstonCHC\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neurodiversit\u00e9 et autisme chez l'adulte - Centres de sant\u00e9 communautaires de Kingston","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/","og_locale":"fr_FR","og_type":"article","og_title":"Neurodiversit\u00e9 et autisme chez l'adulte - Centres de sant\u00e9 communautaires de Kingston","og_description":"Il s'agit d'un atelier d'une heure, soit virtuel\/en ligne, soit en personne. Les animateurs ont une exp\u00e9rience personnelle de la neurodivergence et\/ou de l'autisme adulte, et le programme a \u00e9t\u00e9 d\u00e9velopp\u00e9 par un \u00e9ducateur form\u00e9 ayant \u00e9galement une exp\u00e9rience v\u00e9cue, en collaboration avec la communaut\u00e9 de pratique de la neuroaffirmation \u00e0 Kingston, en Ontario.","og_url":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/","og_site_name":"Centres de sant\u00e9 communautaires de Kingston","article_publisher":"https:\/\/www.facebook.com\/KingstonCHC\/","article_modified_time":"2025-04-15T15:45:47+00:00","og_image":[{"width":851,"height":315,"url":"https:\/\/kchc.ca\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-29T121732.905.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@KingstonCHC","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/","url":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/","name":"Neurodiversit\u00e9 et autisme chez l'adulte - Centres de sant\u00e9 communautaires de Kingston","isPartOf":{"@id":"https:\/\/kchc.ca\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/#primaryimage"},"image":{"@id":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/#primaryimage"},"thumbnailUrl":"https:\/\/kchc.ca\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-29T121732.905.png","datePublished":"2025-03-13T17:38:40+00:00","dateModified":"2025-04-15T15:45:47+00:00","breadcrumb":{"@id":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/#primaryimage","url":"https:\/\/kchc.ca\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-29T121732.905.png","contentUrl":"https:\/\/kchc.ca\/wp-content\/uploads\/2025\/01\/Untitled-design-2025-01-29T121732.905.png","width":851,"height":315},{"@type":"BreadcrumbList","@id":"https:\/\/kchc.ca\/fr\/programs\/neurodiversite-et-autisme-chez-ladulte\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kchc.ca\/fr\/"},{"@type":"ListItem","position":2,"name":"Programs","item":"https:\/\/kchc.ca\/fr\/programs\/"},{"@type":"ListItem","position":3,"name":"Neurodiversit\u00e9 et autisme chez l&#8217;adulte"}]},{"@type":"WebSite","@id":"https:\/\/kchc.ca\/fr\/#website","url":"https:\/\/kchc.ca\/fr\/","name":"Kingston Community Health Centres","description":"","publisher":{"@id":"https:\/\/kchc.ca\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kchc.ca\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/kchc.ca\/fr\/#organization","name":"Kingston Community Health Centres","url":"https:\/\/kchc.ca\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kchc.ca\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/kchc.ca\/wp-content\/uploads\/2024\/06\/KCHC-logo.png","contentUrl":"https:\/\/kchc.ca\/wp-content\/uploads\/2024\/06\/KCHC-logo.png","width":1096,"height":398,"caption":"Kingston Community Health Centres"},"image":{"@id":"https:\/\/kchc.ca\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/KingstonCHC\/","https:\/\/x.com\/KingstonCHC"]}]}},"_links":{"self":[{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/program\/3531","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/program"}],"about":[{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/types\/program"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/media\/3068"}],"wp:attachment":[{"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/media?parent=3531"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/categories?post=3531"},{"taxonomy":"communities","embeddable":true,"href":"https:\/\/kchc.ca\/fr\/wp-json\/wp\/v2\/communities?post=3531"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}